{"id":1852,"date":"2024-04-12T15:45:31","date_gmt":"2024-04-12T15:45:31","guid":{"rendered":"https:\/\/rochade-braunschweig.eu\/?p=1852"},"modified":"2024-04-20T19:34:58","modified_gmt":"2024-04-20T19:34:58","slug":"weihnachtsgeschenk-fuer-den-ksv","status":"publish","type":"post","link":"https:\/\/rochade-braunschweig.eu\/en\/uncategorized\/weihnachtsgeschenk-fuer-den-ksv\/","title":{"rendered":"Weihnachtsgeschenk f\u00fcr den KSV !"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1852\" class=\"elementor elementor-1852\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13ad2c75 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13ad2c75\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e9aa828\" data-id=\"2e9aa828\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47ef19b4 elementor-widget elementor-widget-text-editor\" data-id=\"47ef19b4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><!-- wp:paragraph --><\/p>\n<p>Auf unserer Weihnachtsfeier erhielten wir von unserem Sponsor a3Ds einen Scheck f\u00fcr unsere hervorragende Jugendarbeit ! Vielen Dank hierf\u00fcr ! \ud83d\ude42<br><br><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/rochade-braunschweig.eu\/wp-content\/uploads\/2024\/04\/IMG_5573-169x300.png\" alt=\"\" width=\"169\" height=\"300\" class=\"size-medium wp-image-1853 aligncenter\" srcset=\"https:\/\/rochade-braunschweig.eu\/wp-content\/uploads\/2024\/04\/IMG_5573-169x300.png 169w, https:\/\/rochade-braunschweig.eu\/wp-content\/uploads\/2024\/04\/IMG_5573-576x1024.png 576w, https:\/\/rochade-braunschweig.eu\/wp-content\/uploads\/2024\/04\/IMG_5573-7x12.png 7w, https:\/\/rochade-braunschweig.eu\/wp-content\/uploads\/2024\/04\/IMG_5573.png 750w\" sizes=\"(max-width: 169px) 100vw, 169px\" \/><br>Im Bild: 1. Vorsitzender Steffen Freise und Artur Skuratowicz, Gesch\u00e4ftsf\u00fchrer von a3Ds bei der \u00dcbergabe&nbsp;<\/p>\n<p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Auf unserer Weihnachtsfeier erhielten wir von unserem Sponsor a3Ds einen Scheck f\u00fcr unsere hervorragende Jugendarbeit ! Vielen Dank hierf\u00fcr ! \ud83d\ude42 Im Bild: 1. Vorsitzender Steffen Freise und Artur Skuratowicz, Gesch\u00e4ftsf\u00fchrer von a3Ds bei der \u00dcbergabe&nbsp;<\/p>","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1852","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/rochade-braunschweig.eu\/en\/wp-json\/wp\/v2\/posts\/1852"}],"collection":[{"href":"https:\/\/rochade-braunschweig.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rochade-braunschweig.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rochade-braunschweig.eu\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/rochade-braunschweig.eu\/en\/wp-json\/wp\/v2\/comments?post=1852"}],"version-history":[{"count":6,"href":"https:\/\/rochade-braunschweig.eu\/en\/wp-json\/wp\/v2\/posts\/1852\/revisions"}],"predecessor-version":[{"id":1859,"href":"https:\/\/rochade-braunschweig.eu\/en\/wp-json\/wp\/v2\/posts\/1852\/revisions\/1859"}],"wp:attachment":[{"href":"https:\/\/rochade-braunschweig.eu\/en\/wp-json\/wp\/v2\/media?parent=1852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rochade-braunschweig.eu\/en\/wp-json\/wp\/v2\/categories?post=1852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rochade-braunschweig.eu\/en\/wp-json\/wp\/v2\/tags?post=1852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}